{"id":595294,"date":"2024-10-05T02:42:56","date_gmt":"2024-10-04T23:42:56","guid":{"rendered":"https:\/\/adasatee.com\/product\/natural-green-2\/"},"modified":"2025-02-10T00:52:29","modified_gmt":"2025-02-09T21:52:29","slug":"natural-green-2","status":"publish","type":"product","link":"https:\/\/adasatee.com\/ar\/product\/\u0623\u062e\u0636\u0631-\u0637\u0628\u064a\u0639\u064a-2\/","title":{"rendered":"\u0623\u062e\u0636\u0631 \u0637\u0628\u064a\u0639\u064a"},"content":{"rendered":"<table>\n<tr>\n<th>\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0627\u0645\u0629<\/th>\n<th>\u062a\u0641\u0627\u0635\u064a\u0644<\/th>\n<\/tr>\n<tr>\n<td>\u0627\u0644\u062a\u0639\u0628\u0626\u0629<\/td>\n<td>\u062a\u062d\u062a\u0648\u064a \u0627\u0644\u0639\u0644\u0628\u0629 \u0639\u0644\u0649 \u0639\u062f\u0633\u062a\u064a\u0646<\/td>\n<\/tr>\n<tr>\n<td>\u0627\u0633\u062a\u0628\u062f\u0627\u0644<\/td>\n<td>\u0644\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0627\u0644\u064a\u0648\u0645\u064a<\/td>\n<\/tr>\n<tr>\n<td>\u0645\u0627\u062f\u0629 \u0627\u0644\u0639\u062f\u0633\u0629<\/td>\n<td>38% H2O\u060c 62% Polyhema<\/td>\n<\/tr>\n<tr>\n<td>\u0634\u0631\u064a\u062d\u0629 \u0627\u0644\u0639\u062f\u0633\u0629<\/td>\n<td>\u0639\u062f\u0633\u0629 \u0645\u0644\u0648\u0646\u0629<\/td>\n<\/tr>\n<tr>\n<td>\u0627\u0644\u0642\u0637\u0631<\/td>\n<td>14.2<\/td>\n<\/tr>\n<tr>\n<td>\u0627\u0646\u062d\u0646\u0627\u0621 \u0627\u0644\u0642\u0627\u0639\u062f\u0629<\/td>\n<td>8.6<\/td>\n<\/tr>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0639\u0627\u0645\u0629 \u062a\u0641\u0627\u0635\u064a\u0644 \u0627\u0644\u062a\u0639\u0628\u0626\u0629 1 \u0635\u0646\u062f\u0648\u0642 \u064a\u062d\u062a\u0648\u064a \u0639\u0644\u0649 \u0639\u062f\u0633\u062a\u064a\u0646<\/p>","protected":false},"featured_media":871005,"template":"","meta":{"_aipt_faq_data":""},"product_brand":[819],"product_cat":[210,419],"product_tag":[205],"class_list":{"0":"post-595294","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-dahab","7":"product_cat-dahab","8":"product_cat-natural-daily-1-pair","9":"product_tag-plano","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/product\/595294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/media\/871005"}],"wp:attachment":[{"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/media?parent=595294"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/product_brand?post=595294"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/product_cat?post=595294"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/adasatee.com\/ar\/wp-json\/wp\/v2\/product_tag?post=595294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}